{"id":493,"count":1,"description":"","link":"https:\/\/blog.residenceliguria.com\/it\/tag\/comunicazione\/","name":"comunicazione","slug":"comunicazione","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>comunicazione Archivi - Il Blog di Residence di Liguria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.residenceliguria.com\/de\/tag\/comunicazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"comunicazione Archivi - Il Blog di Residence di Liguria\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.residenceliguria.com\/de\/tag\/comunicazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Il Blog di Residence di Liguria\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2017\/01\/logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"149\" \/>\n\t<meta property=\"og:image:height\" content=\"220\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@liguriavacanze\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/blog.residenceliguria.com\/de\/tag\/comunicazione\/\",\"url\":\"https:\/\/blog.residenceliguria.com\/de\/tag\/comunicazione\/\",\"name\":\"comunicazione Archivi - Il Blog di Residence di Liguria\",\"isPartOf\":{\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.residenceliguria.com\/de\/tag\/comunicazione\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.residenceliguria.com\/de\/tag\/comunicazione\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.residenceliguria.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"comunicazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/#website\",\"url\":\"https:\/\/blog.residenceliguria.com\/it\/\",\"name\":\"Il Blog di Residence di Liguria\",\"description\":\"Idee, suggerimenti, ispirazioni per visitare la Liguria\",\"publisher\":{\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.residenceliguria.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/#organization\",\"name\":\"Il Blog di Residence di Liguria\",\"url\":\"https:\/\/blog.residenceliguria.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2017\/01\/logo.jpg\",\"contentUrl\":\"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2017\/01\/logo.jpg\",\"width\":149,\"height\":220,\"caption\":\"Il Blog di Residence di Liguria\"},\"image\":{\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ResidenceDiLiguria\",\"https:\/\/x.com\/liguriavacanze\",\"https:\/\/www.instagram.com\/residencediliguria\/\",\"https:\/\/it.pinterest.com\/liguriavacanze\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"comunicazione Archivi - Il Blog di Residence di Liguria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.residenceliguria.com\/de\/tag\/comunicazione\/","og_locale":"it_IT","og_type":"article","og_title":"comunicazione Archivi - Il Blog di Residence di Liguria","og_url":"https:\/\/blog.residenceliguria.com\/de\/tag\/comunicazione\/","og_site_name":"Il Blog di Residence di Liguria","og_image":[{"width":149,"height":220,"url":"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2017\/01\/logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@liguriavacanze","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.residenceliguria.com\/de\/tag\/comunicazione\/","url":"https:\/\/blog.residenceliguria.com\/de\/tag\/comunicazione\/","name":"comunicazione Archivi - Il Blog di Residence di Liguria","isPartOf":{"@id":"https:\/\/blog.residenceliguria.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/blog.residenceliguria.com\/de\/tag\/comunicazione\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.residenceliguria.com\/de\/tag\/comunicazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.residenceliguria.com\/it\/"},{"@type":"ListItem","position":2,"name":"comunicazione"}]},{"@type":"WebSite","@id":"https:\/\/blog.residenceliguria.com\/it\/#website","url":"https:\/\/blog.residenceliguria.com\/it\/","name":"Il Blog di Residence di Liguria","description":"Idee, suggerimenti, ispirazioni per visitare la Liguria","publisher":{"@id":"https:\/\/blog.residenceliguria.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.residenceliguria.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/blog.residenceliguria.com\/it\/#organization","name":"Il Blog di Residence di Liguria","url":"https:\/\/blog.residenceliguria.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.residenceliguria.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2017\/01\/logo.jpg","contentUrl":"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2017\/01\/logo.jpg","width":149,"height":220,"caption":"Il Blog di Residence di Liguria"},"image":{"@id":"https:\/\/blog.residenceliguria.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ResidenceDiLiguria","https:\/\/x.com\/liguriavacanze","https:\/\/www.instagram.com\/residencediliguria\/","https:\/\/it.pinterest.com\/liguriavacanze\/"]}]}},"_links":{"self":[{"href":"https:\/\/blog.residenceliguria.com\/it\/wp-json\/wp\/v2\/tags\/493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.residenceliguria.com\/it\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.residenceliguria.com\/it\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.residenceliguria.com\/it\/wp-json\/wp\/v2\/posts?tags=493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}