{"id":207,"count":1,"description":"","link":"https:\/\/blog.residenceliguria.com\/en\/tag\/vignana\/","name":"Vignana","slug":"vignana","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vignana Archivi - Residence Liguria BLOG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.residenceliguria.com\/it\/tag\/vignana\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vignana Archivi - Residence Liguria BLOG\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.residenceliguria.com\/it\/tag\/vignana\/\" \/>\n<meta property=\"og:site_name\" content=\"Residence Liguria BLOG\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2017\/01\/logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"149\" \/>\n\t<meta property=\"og:image:height\" content=\"220\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@liguriavacanze\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/tag\/vignana\/\",\"url\":\"https:\/\/blog.residenceliguria.com\/it\/tag\/vignana\/\",\"name\":\"Vignana Archivi - Residence Liguria BLOG\",\"isPartOf\":{\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/tag\/vignana\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/tag\/vignana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.residenceliguria.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vignana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/#website\",\"url\":\"https:\/\/blog.residenceliguria.com\/it\/\",\"name\":\"Residence Liguria BLOG\",\"description\":\"Ideas, suggestions, inspirations to visit Liguria\",\"publisher\":{\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.residenceliguria.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/#organization\",\"name\":\"Residence Liguria BLOG\",\"url\":\"https:\/\/blog.residenceliguria.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2017\/01\/logo.jpg\",\"contentUrl\":\"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2017\/01\/logo.jpg\",\"width\":149,\"height\":220,\"caption\":\"Residence Liguria BLOG\"},\"image\":{\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ResidenceDiLiguria\",\"https:\/\/x.com\/liguriavacanze\",\"https:\/\/www.instagram.com\/residencediliguria\/\",\"https:\/\/it.pinterest.com\/liguriavacanze\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vignana Archivi - Residence Liguria BLOG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.residenceliguria.com\/it\/tag\/vignana\/","og_locale":"en_US","og_type":"article","og_title":"Vignana Archivi - Residence Liguria BLOG","og_url":"https:\/\/blog.residenceliguria.com\/it\/tag\/vignana\/","og_site_name":"Residence Liguria BLOG","og_image":[{"width":149,"height":220,"url":"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2017\/01\/logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@liguriavacanze","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.residenceliguria.com\/it\/tag\/vignana\/","url":"https:\/\/blog.residenceliguria.com\/it\/tag\/vignana\/","name":"Vignana Archivi - Residence Liguria BLOG","isPartOf":{"@id":"https:\/\/blog.residenceliguria.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/blog.residenceliguria.com\/it\/tag\/vignana\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.residenceliguria.com\/it\/tag\/vignana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.residenceliguria.com\/it\/"},{"@type":"ListItem","position":2,"name":"Vignana"}]},{"@type":"WebSite","@id":"https:\/\/blog.residenceliguria.com\/it\/#website","url":"https:\/\/blog.residenceliguria.com\/it\/","name":"Residence Liguria BLOG","description":"Ideas, suggestions, inspirations to visit Liguria","publisher":{"@id":"https:\/\/blog.residenceliguria.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.residenceliguria.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/blog.residenceliguria.com\/it\/#organization","name":"Residence Liguria BLOG","url":"https:\/\/blog.residenceliguria.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blog.residenceliguria.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2017\/01\/logo.jpg","contentUrl":"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2017\/01\/logo.jpg","width":149,"height":220,"caption":"Residence Liguria BLOG"},"image":{"@id":"https:\/\/blog.residenceliguria.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ResidenceDiLiguria","https:\/\/x.com\/liguriavacanze","https:\/\/www.instagram.com\/residencediliguria\/","https:\/\/it.pinterest.com\/liguriavacanze\/"]}]}},"_links":{"self":[{"href":"https:\/\/blog.residenceliguria.com\/en\/wp-json\/wp\/v2\/tags\/207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.residenceliguria.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.residenceliguria.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.residenceliguria.com\/en\/wp-json\/wp\/v2\/posts?tags=207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}