{"id":1386,"date":"2019-02-13T11:42:12","date_gmt":"2019-02-13T10:42:12","guid":{"rendered":"https:\/\/blog.residenceliguria.com\/?p=1386"},"modified":"2019-02-13T11:42:12","modified_gmt":"2019-02-13T10:42:12","slug":"musei-della-liguria-ecco-i-piu-originali","status":"publish","type":"post","link":"https:\/\/blog.residenceliguria.com\/de\/musei-della-liguria-ecco-i-piu-originali\/","title":{"rendered":"(Italiano) Musei della Liguria: ecco i pi\u00f9 originali"},"content":{"rendered":"<!-- Added by Post\/Page Specific Custom Code plugin, thank you for using! -->\n<style>.contenitorepost {\r\n   height: 480px;\r\n}\r\n@media (max-width: 640px) {\r\n.contenitorepost {\r\n   height: 275px;\r\n}\r\n}<\/style>\n<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-de\">Leider ist der Eintrag nur auf <a href=\"https:\/\/blog.residenceliguria.com\/it\/wp-json\/wp\/v2\/posts\/1386\" class=\"qtranxs-available-language-link qtranxs-available-language-link-it\" title=\"Italiano\">Italiano<\/a> verf\u00fcgbar.<\/p>","protected":false},"excerpt":{"rendered":"<p>Leider ist der Eintrag nur auf Italiano verf\u00fcgbar.<\/p>\n","protected":false},"author":1,"featured_media":1394,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,5],"tags":[356,372,374,371,373,355,375,370],"class_list":["post-1386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destinazioni","category-liguria","tag-grotte-di-toirano","tag-miniere-di-gabatesa","tag-museo-del-mare-genova","tag-museo-della-stregoneria","tag-museo-galata","tag-museo-paleontologico-silvio-lai","tag-museo-tecnico-navale-la-spezia","tag-villa-grock"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>(Italiano) Musei della Liguria: ecco i pi\u00f9 originali - Residence Liguria BLOG<\/title>\n<meta name=\"description\" content=\"I musei di cui vogliamo parlarvi oggi sono quelli pi\u00f9 originali e strani da visitare in Liguria. Musei poco noti, che solo in Liguria potrete trovare.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"(Italiano) Musei della Liguria: ecco i pi\u00f9 originali - Residence Liguria BLOG\" \/>\n<meta property=\"og:description\" content=\"I musei di cui vogliamo parlarvi oggi sono quelli pi\u00f9 originali e strani da visitare in Liguria. Musei poco noti, che solo in Liguria potrete trovare.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/\" \/>\n<meta property=\"og:site_name\" content=\"Residence Liguria BLOG\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ResidenceDiLiguria\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-13T10:42:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2019\/02\/Villa-grock-esterno.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"785\" \/>\n\t<meta property=\"og:image:height\" content=\"589\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ResidenceLiguria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@liguriavacanze\" \/>\n<meta name=\"twitter:site\" content=\"@liguriavacanze\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"ResidenceLiguria\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/\"},\"author\":{\"name\":\"ResidenceLiguria\",\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/#\/schema\/person\/56d50e78d9e43765ffcfce591fb5d129\"},\"headline\":\"(Italiano) Musei della Liguria: ecco i pi\u00f9 originali\",\"datePublished\":\"2019-02-13T10:42:12+00:00\",\"dateModified\":\"2019-02-13T10:42:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/\"},\"wordCount\":778,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/#organization\"},\"image\":{\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2019\/02\/Villa-grock-esterno.jpg\",\"keywords\":[\"Grotte di Toirano\",\"miniere di Gabatesa\",\"Museo del mare Genova\",\"museo della stregoneria\",\"Museo Galata\",\"Museo Paleontologico Silvio Lai\",\"Museo Tecnico Navale La Spezia\",\"Villa Grock\"],\"articleSection\":[\"Ziel\",\"Liguria\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/\",\"url\":\"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/\",\"name\":\"(Italiano) Musei della Liguria: ecco i pi\u00f9 originali - Residence Liguria BLOG\",\"isPartOf\":{\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2019\/02\/Villa-grock-esterno.jpg\",\"datePublished\":\"2019-02-13T10:42:12+00:00\",\"dateModified\":\"2019-02-13T10:42:12+00:00\",\"description\":\"I musei di cui vogliamo parlarvi oggi sono quelli pi\u00f9 originali e strani da visitare in Liguria. Musei poco noti, che solo in Liguria potrete trovare.\",\"breadcrumb\":{\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/#primaryimage\",\"url\":\"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2019\/02\/Villa-grock-esterno.jpg\",\"contentUrl\":\"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2019\/02\/Villa-grock-esterno.jpg\",\"width\":785,\"height\":589},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.residenceliguria.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Musei della Liguria: ecco i pi\u00f9 originali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/#website\",\"url\":\"https:\/\/blog.residenceliguria.com\/it\/\",\"name\":\"Residence Liguria BLOG\",\"description\":\"Ideen, Anregungen, Inspirationen, um Ligurien zu besuchen\",\"publisher\":{\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.residenceliguria.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/#organization\",\"name\":\"Residence Liguria BLOG\",\"url\":\"https:\/\/blog.residenceliguria.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2017\/01\/logo.jpg\",\"contentUrl\":\"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2017\/01\/logo.jpg\",\"width\":149,\"height\":220,\"caption\":\"Residence Liguria BLOG\"},\"image\":{\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ResidenceDiLiguria\",\"https:\/\/x.com\/liguriavacanze\",\"https:\/\/www.instagram.com\/residencediliguria\/\",\"https:\/\/it.pinterest.com\/liguriavacanze\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.residenceliguria.com\/it\/#\/schema\/person\/56d50e78d9e43765ffcfce591fb5d129\",\"name\":\"ResidenceLiguria\",\"url\":\"https:\/\/blog.residenceliguria.com\/de\/author\/residenceliguria\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"(Italiano) Musei della Liguria: ecco i pi\u00f9 originali - Residence Liguria BLOG","description":"I musei di cui vogliamo parlarvi oggi sono quelli pi\u00f9 originali e strani da visitare in Liguria. Musei poco noti, che solo in Liguria potrete trovare.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/","og_locale":"de_DE","og_type":"article","og_title":"(Italiano) Musei della Liguria: ecco i pi\u00f9 originali - Residence Liguria BLOG","og_description":"I musei di cui vogliamo parlarvi oggi sono quelli pi\u00f9 originali e strani da visitare in Liguria. Musei poco noti, che solo in Liguria potrete trovare.","og_url":"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/","og_site_name":"Residence Liguria BLOG","article_publisher":"https:\/\/www.facebook.com\/ResidenceDiLiguria","article_published_time":"2019-02-13T10:42:12+00:00","og_image":[{"width":785,"height":589,"url":"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2019\/02\/Villa-grock-esterno.jpg","type":"image\/jpeg"}],"author":"ResidenceLiguria","twitter_card":"summary_large_image","twitter_creator":"@liguriavacanze","twitter_site":"@liguriavacanze","twitter_misc":{"Verfasst von":"ResidenceLiguria","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/#article","isPartOf":{"@id":"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/"},"author":{"name":"ResidenceLiguria","@id":"https:\/\/blog.residenceliguria.com\/it\/#\/schema\/person\/56d50e78d9e43765ffcfce591fb5d129"},"headline":"(Italiano) Musei della Liguria: ecco i pi\u00f9 originali","datePublished":"2019-02-13T10:42:12+00:00","dateModified":"2019-02-13T10:42:12+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/"},"wordCount":778,"commentCount":0,"publisher":{"@id":"https:\/\/blog.residenceliguria.com\/it\/#organization"},"image":{"@id":"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2019\/02\/Villa-grock-esterno.jpg","keywords":["Grotte di Toirano","miniere di Gabatesa","Museo del mare Genova","museo della stregoneria","Museo Galata","Museo Paleontologico Silvio Lai","Museo Tecnico Navale La Spezia","Villa Grock"],"articleSection":["Ziel","Liguria"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/","url":"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/","name":"(Italiano) Musei della Liguria: ecco i pi\u00f9 originali - Residence Liguria BLOG","isPartOf":{"@id":"https:\/\/blog.residenceliguria.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/#primaryimage"},"image":{"@id":"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2019\/02\/Villa-grock-esterno.jpg","datePublished":"2019-02-13T10:42:12+00:00","dateModified":"2019-02-13T10:42:12+00:00","description":"I musei di cui vogliamo parlarvi oggi sono quelli pi\u00f9 originali e strani da visitare in Liguria. Musei poco noti, che solo in Liguria potrete trovare.","breadcrumb":{"@id":"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/#primaryimage","url":"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2019\/02\/Villa-grock-esterno.jpg","contentUrl":"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2019\/02\/Villa-grock-esterno.jpg","width":785,"height":589},{"@type":"BreadcrumbList","@id":"https:\/\/blog.residenceliguria.com\/it\/musei-della-liguria-ecco-i-piu-originali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.residenceliguria.com\/it\/"},{"@type":"ListItem","position":2,"name":"Musei della Liguria: ecco i pi\u00f9 originali"}]},{"@type":"WebSite","@id":"https:\/\/blog.residenceliguria.com\/it\/#website","url":"https:\/\/blog.residenceliguria.com\/it\/","name":"Residence Liguria BLOG","description":"Ideen, Anregungen, Inspirationen, um Ligurien zu besuchen","publisher":{"@id":"https:\/\/blog.residenceliguria.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.residenceliguria.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blog.residenceliguria.com\/it\/#organization","name":"Residence Liguria BLOG","url":"https:\/\/blog.residenceliguria.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.residenceliguria.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2017\/01\/logo.jpg","contentUrl":"https:\/\/blog.residenceliguria.com\/wp-content\/uploads\/2017\/01\/logo.jpg","width":149,"height":220,"caption":"Residence Liguria BLOG"},"image":{"@id":"https:\/\/blog.residenceliguria.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ResidenceDiLiguria","https:\/\/x.com\/liguriavacanze","https:\/\/www.instagram.com\/residencediliguria\/","https:\/\/it.pinterest.com\/liguriavacanze\/"]},{"@type":"Person","@id":"https:\/\/blog.residenceliguria.com\/it\/#\/schema\/person\/56d50e78d9e43765ffcfce591fb5d129","name":"ResidenceLiguria","url":"https:\/\/blog.residenceliguria.com\/de\/author\/residenceliguria\/"}]}},"wps_subtitle":"Liguria: i musei pi\u00f9 strani da visitare","_links":{"self":[{"href":"https:\/\/blog.residenceliguria.com\/de\/wp-json\/wp\/v2\/posts\/1386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.residenceliguria.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.residenceliguria.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.residenceliguria.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.residenceliguria.com\/de\/wp-json\/wp\/v2\/comments?post=1386"}],"version-history":[{"count":0,"href":"https:\/\/blog.residenceliguria.com\/de\/wp-json\/wp\/v2\/posts\/1386\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.residenceliguria.com\/de\/wp-json\/wp\/v2\/media\/1394"}],"wp:attachment":[{"href":"https:\/\/blog.residenceliguria.com\/de\/wp-json\/wp\/v2\/media?parent=1386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.residenceliguria.com\/de\/wp-json\/wp\/v2\/categories?post=1386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.residenceliguria.com\/de\/wp-json\/wp\/v2\/tags?post=1386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}